{"id":272,"date":"2020-06-12T10:14:00","date_gmt":"2020-06-12T13:14:00","guid":{"rendered":"https:\/\/www.anfitriaoprime.com.br\/blog\/?p=272"},"modified":"2024-06-05T11:36:05","modified_gmt":"2024-06-05T14:36:05","slug":"distanciamento-social-em-imovel-de-temporada","status":"publish","type":"post","link":"https:\/\/www.anfitriaoprime.com.br\/blog\/distanciamento-social-em-imovel-de-temporada\/","title":{"rendered":"Seu im\u00f3vel de temporada pode se adequar ao distanciamento social de outras fam\u00edlias"},"content":{"rendered":"\r\n<p>O distanciamento social, fundamental e obrigat\u00f3rio, para conter a dissemina\u00e7\u00e3o do coronav\u00edrus trouxe altera\u00e7\u00f5es que mudaram subitamente a rotina e a estrutura de trabalho e estudo da maior parte das pessoas.<\/p>\r\n\r\n\r\n\r\n<p>Com isso, for\u00e7ou as empresas a manterem toda ou parte da equipe executando as fun\u00e7\u00f5es profissionais direto do lar, junto do aprendizado das crian\u00e7as e adolescentes.<\/p>\r\n\r\n\r\n\r\n<p>Trabalhar em um espa\u00e7o que proporcione liberdade profissional, flexibilidade de hor\u00e1rio e ainda diminui\u00e7\u00e3o das horas no tr\u00e2nsito \u00e9 um dos atrativos ao home office e o que muitos profissionais almejam para suas carreiras.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>A possibilidade de ter intervalos mais confort\u00e1veis e mais presen\u00e7a na rotina da fam\u00edlia faz com que esse seja um sistema desejado para desfrutar de mais qualidade de vida. Entretanto, ningu\u00e9m imaginou que o emprego dos sonhos viria \u00e0s custas das raz\u00f5es atuais.\u00a0<\/p>\r\n\r\n\r\n\r\n<h2>As maiores dificuldades do distanciamento social<\/h2>\r\n\r\n\r\n\r\n<p>A maior dificuldade de pessoas que fazem home office geralmente est\u00e1 no aspecto comportamental mediante a poss\u00edveis distra\u00e7\u00f5es. Seguir a rotina de modo habitual j\u00e1 \u00e9 uma tarefa que se torna desafiadora quando se tem diversas op\u00e7\u00f5es de conforto \u00e0 disposi\u00e7\u00e3o.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>Acrescentar \u00e0 isso as necessidades de adapta\u00e7\u00e3o com a nova rotina, ao trabalho e adequa\u00e7\u00e3o de outras pessoas, possivelmente o homeschooling das crian\u00e7as, al\u00e9m de manter a organiza\u00e7\u00e3o e a limpeza da casa, o lazer e as refei\u00e7\u00f5es em meio ao que estamos vivendo no momento, pode beirar o imposs\u00edvel.\u00a0<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"750\" height=\"500\" class=\"wp-image-276\" src=\"https:\/\/www.anfitriaoprime.com.br\/blog\/wp-content\/uploads\/2020\/07\/home-office-distanciamento-social-coronav\u00edrus.jpg\" alt=\"\" srcset=\"https:\/\/www.anfitriaoprime.com.br\/blog\/wp-content\/uploads\/2020\/07\/home-office-distanciamento-social-coronav\u00edrus.jpg 750w, https:\/\/www.anfitriaoprime.com.br\/blog\/wp-content\/uploads\/2020\/07\/home-office-distanciamento-social-coronav\u00edrus-300x200.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\r\n<figcaption>Voc\u00ea pode adaptar o seu im\u00f3vel de temporada para o distanciamento social de outros grupos.<\/figcaption>\r\n<\/figure>\r\n\r\n\r\n\r\n<p>Para mais do que j\u00e1 foi dito, diversas fam\u00edlias atualmente moram em im\u00f3veis pequenos que sustentam a rotina normal familiar, ou seja, contexto em que cada membro da fam\u00edlia tem seus compromissos fora do ambiente dom\u00e9stico e particular.<\/p>\r\n\r\n\r\n\r\n<p>E n\u00e3o possuem na resid\u00eancia quartos extras que poderiam ser utilizados como escrit\u00f3rio fazendo com que os c\u00f4modos fiquem divididos desconfortavelmente resultando em um ambiente pouco preparado e de dif\u00edcil concentra\u00e7\u00e3o.<\/p>\r\n\r\n\r\n\r\n<p>Com a necessidade do distanciamento social, as fun\u00e7\u00f5es pessoais e profissionais de cada um se juntaram causando no lar uma superlota\u00e7\u00e3o de demandas. E o que era uma das principais caracter\u00edsticas do home office, delimitar o espa\u00e7o de trabalho para separar o pessoal do profissional, se tornou uma das maiores dificuldades.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>Conciliar em tempo integral a conviv\u00eancia familiar, os compromissos profissionais e a escola dentro do mesmo espa\u00e7o pode ser um tanto quanto desafiador, j\u00e1 que a possibilidade de todos os integrantes da resid\u00eancia precisarem usar o \u00fanico c\u00f4modo apropriado para a tarefa \u00e9 grande.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>Em fun\u00e7\u00e3o disso, \u00e9 interessante voc\u00ea pensar na possibilidade da sua casa de temporada servir para essas fam\u00edlias, que possuem melhor condi\u00e7\u00e3o, enfrentarem o distanciamento social e todos os afazeres que v\u00eam implicado nessa circunst\u00e2ncia.\u00a0<\/p>\r\n\r\n\r\n\r\n<h2><strong>As necessidades do home office e homeschooling<\/strong><\/h2>\r\n\r\n\r\n\r\n<p>A infraestrutura que cada um precisa para trabalhar e estudar, como computador, material, fone de ouvido etc, s\u00e3o ferramentas que eles possivelmente j\u00e1 ter\u00e3o. O b\u00e1sico para cada um manter uma rotina disciplinada para garantir a produtividade \u00e9 ter:<\/p>\r\n\r\n\r\n\r\n<ul>\r\n<li>Espa\u00e7o f\u00edsico separado e adequado;<\/li>\r\n<li>M\u00f3veis funcionais;<\/li>\r\n<li>Internet com wifi;<\/li>\r\n<li>Rotina com cronograma de atividades.<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"750\" height=\"501\" class=\"wp-image-275\" src=\"https:\/\/www.anfitriaoprime.com.br\/blog\/wp-content\/uploads\/2020\/07\/homeschooling-distanciamento-social-coronav\u00edrus.jpg\" alt=\"garoto-homeschooling-distanciamento-social\" srcset=\"https:\/\/www.anfitriaoprime.com.br\/blog\/wp-content\/uploads\/2020\/07\/homeschooling-distanciamento-social-coronav\u00edrus.jpg 750w, https:\/\/www.anfitriaoprime.com.br\/blog\/wp-content\/uploads\/2020\/07\/homeschooling-distanciamento-social-coronav\u00edrus-300x200.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\r\n<figcaption>O distanciamento social fez com que as fun\u00e7\u00f5es profissionais e o aprendizado das crian\u00e7as e adolescentes se juntassem no espa\u00e7o f\u00edsico do lar.<\/figcaption>\r\n<\/figure>\r\n\r\n\r\n\r\n<p>Assim, cada um dos membros consegue criar uma rotina pr\u00f3pria e pode colocar um limite entre o ambiente pessoal e profissional, evitando que se prejudiquem.<\/p>\r\n\r\n\r\n\r\n<p>Isto posto, n\u00f3s separamos uma s\u00e9rie de dicas para voc\u00ea adaptar o seu im\u00f3vel a essa\u00a0oportunidade.<\/p>\r\n\r\n\r\n\r\n<h2><strong>Como o seu im\u00f3vel de temporada pode se adequar ao distanciamento social de outras fam\u00edlias?<\/strong><\/h2>\r\n\r\n\r\n\r\n<p>Para come\u00e7ar o seu h\u00f3spede precisa de um ambiente que seja bem arejado, por meio de janelas, ventilador ou ar condicionado, que tenha uma ac\u00fastica legal e excelente ilumina\u00e7\u00e3o, de prefer\u00eancia com luz natural, pois para reuni\u00f5es esses pontos s\u00e3o imprescind\u00edveis.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>Al\u00e9m disso, voc\u00ea pode equipar os c\u00f4modos com m\u00f3veis de escrit\u00f3rio, como mesas espa\u00e7osas e\/ou com gavetas, cadeiras confort\u00e1veis e estantes para documentos.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>Possuir um plano de internet com wifi que ofere\u00e7a uma conex\u00e3o com boa velocidade \u00e9 o ideal, j\u00e1 que haver\u00e1 momentos em que todos usar\u00e3o a internet ao mesmo tempo.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>Por fim, a decora\u00e7\u00e3o tamb\u00e9m \u00e9 super relevante, afinal esse espa\u00e7o far\u00e1 parte da vida pessoal e profissional dos seus h\u00f3spedes, sendo fundamental manter o conforto de um lar e a seriedade de um ambiente de trabalho.<\/p>\r\n\r\n\r\n\r\n<p>Existem diversos estudos que comprovam a necessidade de um visual agrad\u00e1vel para incentivar a concentra\u00e7\u00e3o e a criatividade. Acima de tudo, os visitantes desejar\u00e3o comodidade e objetividade.<\/p>\r\n\r\n\r\n\r\n<h2><strong>O que fazer depois de adaptar o seu im\u00f3vel?<\/strong><\/h2>\r\n\r\n\r\n\r\n<p>Se voc\u00ea chegou at\u00e9 aqui deve estar se perguntando: O que eu fa\u00e7o depois de adaptar a minha propriedade? Nada! N\u00f3s, do <a href=\"https:\/\/www.anfitriaoprime.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"undefined (opens in a new tab)\">Anfitri\u00e3o Prime<\/a>, te ajudamos a fazer as melhores fotos e a destacar as caracter\u00edsticas mais marcantes do seu im\u00f3vel de temporada.<\/p>\r\n\r\n\r\n\r\n<p>Al\u00e9m disso, a publica\u00e7\u00e3o e a divulga\u00e7\u00e3o de todas as novidades nos principais sites de reserva do Brasil e do mundo, incluindo Airbnb, Vrbo (antigo Alugue Temporada) e Booking.com fica por nossa conta.\u00a0\u00c9 s\u00f3 escolher qual <a href=\"https:\/\/www.anfitriaoprime.com.br\/#planos\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"undefined (opens in a new tab)\">plano<\/a> mais combina com seu im\u00f3vel e as suas necessidades.<\/p>\r\n\r\n\r\n\r\n<p>Leia tamb\u00e9m os outros textos da s\u00e9rie <a href=\"https:\/\/www.anfitriaoprime.com.br\/blog\/category\/aluguel-de-temporada-x-coronavirus\/\">Aluguel de temporada x coronav\u00edrus<\/a>.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>O distanciamento social, fundamental e obrigat\u00f3rio, para conter a dissemina\u00e7\u00e3o do coronav\u00edrus trouxe altera\u00e7\u00f5es que mudaram subitamente a rotina e a estrutura de trabalho e estudo da maior parte das pessoas. Com isso, for\u00e7ou as empresas a manterem toda ou parte da equipe executando as fun\u00e7\u00f5es profissionais direto do lar, junto do aprendizado das crian\u00e7as [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":274,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[36,7],"tags":[27,19,20,24,23],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Seu im\u00f3vel de temporada pode se adequar ao distanciamento social de outras fam\u00edlias - Blog Anfitri\u00e3o Prime: Ganhe dinheiro com aluguel de temporada.<\/title>\n<meta name=\"description\" content=\"Entenda quais s\u00e3o as principais necessidades do home office e homeschooling e adapte o seu im\u00f3vel para o distanciamento social de outras fam\u00edlias.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.anfitriaoprime.com.br\/blog\/distanciamento-social-em-imovel-de-temporada\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seu im\u00f3vel de temporada pode se adequar ao distanciamento social de outras fam\u00edlias - Blog Anfitri\u00e3o Prime: Ganhe dinheiro com aluguel de temporada.\" \/>\n<meta property=\"og:description\" content=\"Entenda quais s\u00e3o as principais necessidades do home office e homeschooling e adapte o seu im\u00f3vel para o distanciamento social de outras fam\u00edlias.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.anfitriaoprime.com.br\/blog\/distanciamento-social-em-imovel-de-temporada\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Anfitri\u00e3o Prime: Ganhe dinheiro com aluguel de temporada.\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-12T13:14:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-05T14:36:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.anfitriaoprime.com.br\/blog\/wp-content\/uploads\/2020\/07\/stay-home-fique-em-casa-distanciamento-social-coronav\u00edrus-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anfitriaoprime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"anfitriaoprime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.anfitriaoprime.com.br\/blog\/distanciamento-social-em-imovel-de-temporada\/\",\"url\":\"https:\/\/www.anfitriaoprime.com.br\/blog\/distanciamento-social-em-imovel-de-temporada\/\",\"name\":\"Seu im\u00f3vel de temporada pode se adequar ao distanciamento social de outras fam\u00edlias - Blog Anfitri\u00e3o Prime: Ganhe dinheiro com aluguel de temporada.\",\"isPartOf\":{\"@id\":\"https:\/\/www.anfitriaoprime.com.br\/blog\/#website\"},\"datePublished\":\"2020-06-12T13:14:00+00:00\",\"dateModified\":\"2024-06-05T14:36:05+00:00\",\"author\":{\"@id\":\"https:\/\/www.anfitriaoprime.com.br\/blog\/#\/schema\/person\/1938a3ae114d1c7ab2db79ebd2bb7bdd\"},\"description\":\"Entenda quais s\u00e3o as principais necessidades do home office e homeschooling e adapte o seu im\u00f3vel para o distanciamento social de outras fam\u00edlias.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.anfitriaoprime.com.br\/blog\/distanciamento-social-em-imovel-de-temporada\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.anfitriaoprime.com.br\/blog\/distanciamento-social-em-imovel-de-temporada\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.anfitriaoprime.com.br\/blog\/distanciamento-social-em-imovel-de-temporada\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.anfitriaoprime.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seu im\u00f3vel de temporada pode se adequar ao distanciamento social de outras fam\u00edlias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.anfitriaoprime.com.br\/blog\/#website\",\"url\":\"https:\/\/www.anfitriaoprime.com.br\/blog\/\",\"name\":\"Blog Anfitri\u00e3o Prime - Gest\u00e3o de propriedade para aluguel de temporada\",\"description\":\"No blog do Anfitri\u00e3o Prime voc\u00ea encontra dicas e informa\u00e7\u00f5es sobre o mercado de aluguel de temporada escrito por anfitri\u00f5es profissionais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.anfitriaoprime.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.anfitriaoprime.com.br\/blog\/#\/schema\/person\/1938a3ae114d1c7ab2db79ebd2bb7bdd\",\"name\":\"anfitriaoprime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.anfitriaoprime.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1adb0796a2d3d9f29c7b10e53d35b528?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1adb0796a2d3d9f29c7b10e53d35b528?s=96&d=mm&r=g\",\"caption\":\"anfitriaoprime\"},\"sameAs\":[\"https:\/\/www.anfitriaoprime.com.br\/blog\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seu im\u00f3vel de temporada pode se adequar ao distanciamento social de outras fam\u00edlias - Blog Anfitri\u00e3o Prime: Ganhe dinheiro com aluguel de temporada.","description":"Entenda quais s\u00e3o as principais necessidades do home office e homeschooling e adapte o seu im\u00f3vel para o distanciamento social de outras fam\u00edlias.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.anfitriaoprime.com.br\/blog\/distanciamento-social-em-imovel-de-temporada\/","og_locale":"pt_BR","og_type":"article","og_title":"Seu im\u00f3vel de temporada pode se adequar ao distanciamento social de outras fam\u00edlias - Blog Anfitri\u00e3o Prime: Ganhe dinheiro com aluguel de temporada.","og_description":"Entenda quais s\u00e3o as principais necessidades do home office e homeschooling e adapte o seu im\u00f3vel para o distanciamento social de outras fam\u00edlias.","og_url":"https:\/\/www.anfitriaoprime.com.br\/blog\/distanciamento-social-em-imovel-de-temporada\/","og_site_name":"Blog Anfitri\u00e3o Prime: Ganhe dinheiro com aluguel de temporada.","article_published_time":"2020-06-12T13:14:00+00:00","article_modified_time":"2024-06-05T14:36:05+00:00","og_image":[{"width":1920,"height":550,"url":"https:\/\/www.anfitriaoprime.com.br\/blog\/wp-content\/uploads\/2020\/07\/stay-home-fique-em-casa-distanciamento-social-coronav\u00edrus-1.jpg","type":"image\/jpeg"}],"author":"anfitriaoprime","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"anfitriaoprime","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.anfitriaoprime.com.br\/blog\/distanciamento-social-em-imovel-de-temporada\/","url":"https:\/\/www.anfitriaoprime.com.br\/blog\/distanciamento-social-em-imovel-de-temporada\/","name":"Seu im\u00f3vel de temporada pode se adequar ao distanciamento social de outras fam\u00edlias - Blog Anfitri\u00e3o Prime: Ganhe dinheiro com aluguel de temporada.","isPartOf":{"@id":"https:\/\/www.anfitriaoprime.com.br\/blog\/#website"},"datePublished":"2020-06-12T13:14:00+00:00","dateModified":"2024-06-05T14:36:05+00:00","author":{"@id":"https:\/\/www.anfitriaoprime.com.br\/blog\/#\/schema\/person\/1938a3ae114d1c7ab2db79ebd2bb7bdd"},"description":"Entenda quais s\u00e3o as principais necessidades do home office e homeschooling e adapte o seu im\u00f3vel para o distanciamento social de outras fam\u00edlias.","breadcrumb":{"@id":"https:\/\/www.anfitriaoprime.com.br\/blog\/distanciamento-social-em-imovel-de-temporada\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.anfitriaoprime.com.br\/blog\/distanciamento-social-em-imovel-de-temporada\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.anfitriaoprime.com.br\/blog\/distanciamento-social-em-imovel-de-temporada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.anfitriaoprime.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Seu im\u00f3vel de temporada pode se adequar ao distanciamento social de outras fam\u00edlias"}]},{"@type":"WebSite","@id":"https:\/\/www.anfitriaoprime.com.br\/blog\/#website","url":"https:\/\/www.anfitriaoprime.com.br\/blog\/","name":"Blog Anfitri\u00e3o Prime - Gest\u00e3o de propriedade para aluguel de temporada","description":"No blog do Anfitri\u00e3o Prime voc\u00ea encontra dicas e informa\u00e7\u00f5es sobre o mercado de aluguel de temporada escrito por anfitri\u00f5es profissionais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.anfitriaoprime.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.anfitriaoprime.com.br\/blog\/#\/schema\/person\/1938a3ae114d1c7ab2db79ebd2bb7bdd","name":"anfitriaoprime","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.anfitriaoprime.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1adb0796a2d3d9f29c7b10e53d35b528?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1adb0796a2d3d9f29c7b10e53d35b528?s=96&d=mm&r=g","caption":"anfitriaoprime"},"sameAs":["https:\/\/www.anfitriaoprime.com.br\/blog"]}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.anfitriaoprime.com.br\/blog\/wp-json\/wp\/v2\/posts\/272"}],"collection":[{"href":"https:\/\/www.anfitriaoprime.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.anfitriaoprime.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.anfitriaoprime.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.anfitriaoprime.com.br\/blog\/wp-json\/wp\/v2\/comments?post=272"}],"version-history":[{"count":7,"href":"https:\/\/www.anfitriaoprime.com.br\/blog\/wp-json\/wp\/v2\/posts\/272\/revisions"}],"predecessor-version":[{"id":6273,"href":"https:\/\/www.anfitriaoprime.com.br\/blog\/wp-json\/wp\/v2\/posts\/272\/revisions\/6273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.anfitriaoprime.com.br\/blog\/wp-json\/wp\/v2\/media\/274"}],"wp:attachment":[{"href":"https:\/\/www.anfitriaoprime.com.br\/blog\/wp-json\/wp\/v2\/media?parent=272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.anfitriaoprime.com.br\/blog\/wp-json\/wp\/v2\/categories?post=272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.anfitriaoprime.com.br\/blog\/wp-json\/wp\/v2\/tags?post=272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}